{"id":9126,"date":"2018-10-23T15:45:28","date_gmt":"2018-10-23T15:45:28","guid":{"rendered":"https:\/\/www.biocabaz.pt\/web\/?post_type=product&#038;p=9126"},"modified":"2022-03-11T12:02:07","modified_gmt":"2022-03-11T12:02:07","slug":"galetes-finas-de-arroz-integral-bio-lima","status":"publish","type":"product","link":"https:\/\/biocabaz.pt\/web\/produto\/galetes-finas-de-arroz-integral-bio-lima\/","title":{"rendered":"GALETES FINAS DE ARROZ INTEGRAL BIO LIMA"},"content":{"rendered":"<p><strong>Descri\u00e7\u00e3o <\/strong><br \/>\n\t\t\t\tIngredientes: Arroz integral * (99,7%), sal marinho. *de Agricultura Biol\u00f3gica. Pobre em gorduras saturadas. Sem gl\u00faten.<\/p>\n<p><strong>Dados Nutricionais<\/strong><br \/>\n\t\t\t\tDeclara\u00e7\u00e3o Nutricional por 100g:<br \/> Energia: 389kcal\/1627kJ;<br \/> Prote\u00ednas: 7,8g;<br \/> Gl\u00faten: 0,0g;<br \/> Hidratos de Carbono: 81,1g &#8211; dos quais a\u00e7\u00facares: 2,0g;<br \/> L\u00edpidos: 3,2g &#8211; dos quais saturados: 1,0g;<br \/> Fibra Alimentar: 2,4g;<br \/> S\u00f3dio: 0,13g.<\/p>\n<p><strong>Modo Utiliza\u00e7\u00e3o<\/strong><br \/>Conservar em local seco e fresco.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Descri\u00e7\u00e3o Ingredientes: Arroz integral * (99,7%), sal marinho. *de Agricultura Biol\u00f3gica. Pobre em gorduras saturadas. Sem gl\u00faten. Dados Nutricionais Declara\u00e7\u00e3o Nutricional por 100g: Energia: 389kcal\/1627kJ; Prote\u00ednas: 7,8g; Gl\u00faten: 0,0g; Hidratos de Carbono: 81,1g &#8211; dos quais a\u00e7\u00facares: 2,0g; L\u00edpidos: 3,2g &#8211; dos quais saturados: 1,0g; Fibra Alimentar: 2,4g; S\u00f3dio: 0,13g. Modo Utiliza\u00e7\u00e3oConservar em local seco [&hellip;]<\/p>\n","protected":false},"featured_media":9127,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_cat":[54,29],"product_tag":[],"class_list":["post-9126","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-alimentos-sem-gluten","product_cat-bolachas_e_snacks"],"bundle_layout":"","bundled_by":[],"bundled_items":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>GALETES FINAS DE ARROZ INTEGRAL BIO LIMA<\/title>\n<meta name=\"description\" content=\"GALETES FINAS DE ARROZ INTEGRAL BIO LIMA\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.biocabaz.pt\/web\/en\/produto\/galetes-finas-de-arroz-integral-bio-lima\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:locale:alternate\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GALETES FINAS DE ARROZ INTEGRAL BIO LIMA\" \/>\n<meta property=\"og:description\" content=\"GALETES FINAS DE ARROZ INTEGRAL BIO LIMA\" \/>\n<meta property=\"og:url\" content=\"https:\/\/biocabaz.pt\/web\/produto\/galetes-finas-de-arroz-integral-bio-lima\/\" \/>\n<meta property=\"og:site_name\" content=\"BIOCABAZ - CABAZES BIOL\u00d3GICOS\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-11T12:02:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.biocabaz.pt\/web\/wp-conteudos\/uploads\/2018\/10\/GALETES-FINAS-DE-ARROZ-INTEGRAL-BIO-LIMA.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.biocabaz.pt\/web\/en\/produto\/galetes-finas-de-arroz-integral-bio-lima\/\",\"url\":\"https:\/\/www.biocabaz.pt\/web\/en\/produto\/galetes-finas-de-arroz-integral-bio-lima\/\",\"name\":\"GALETES FINAS DE ARROZ INTEGRAL BIO LIMA\",\"isPartOf\":{\"@id\":\"https:\/\/biocabaz.pt\/web\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.biocabaz.pt\/web\/en\/produto\/galetes-finas-de-arroz-integral-bio-lima\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.biocabaz.pt\/web\/en\/produto\/galetes-finas-de-arroz-integral-bio-lima\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.biocabaz.pt\/web\/wp-conteudos\/uploads\/2018\/10\/GALETES-FINAS-DE-ARROZ-INTEGRAL-BIO-LIMA.jpg\",\"datePublished\":\"2018-10-23T15:45:28+00:00\",\"dateModified\":\"2022-03-11T12:02:07+00:00\",\"description\":\"GALETES FINAS DE ARROZ INTEGRAL BIO LIMA\",\"breadcrumb\":{\"@id\":\"https:\/\/www.biocabaz.pt\/web\/en\/produto\/galetes-finas-de-arroz-integral-bio-lima\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.biocabaz.pt\/web\/en\/produto\/galetes-finas-de-arroz-integral-bio-lima\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/www.biocabaz.pt\/web\/en\/produto\/galetes-finas-de-arroz-integral-bio-lima\/#primaryimage\",\"url\":\"https:\/\/www.biocabaz.pt\/web\/wp-conteudos\/uploads\/2018\/10\/GALETES-FINAS-DE-ARROZ-INTEGRAL-BIO-LIMA.jpg\",\"contentUrl\":\"https:\/\/www.biocabaz.pt\/web\/wp-conteudos\/uploads\/2018\/10\/GALETES-FINAS-DE-ARROZ-INTEGRAL-BIO-LIMA.jpg\",\"width\":512,\"height\":512,\"caption\":\"GALETES FINAS DE ARROZ INTEGRAL BIO LIMA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.biocabaz.pt\/web\/en\/produto\/galetes-finas-de-arroz-integral-bio-lima\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/biocabaz.pt\/web\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/biocabaz.pt\/web\/en\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"LIMA ORGANIC WHOLEGRAIN RICE CAKES\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/biocabaz.pt\/web\/en\/#website\",\"url\":\"https:\/\/biocabaz.pt\/web\/en\/\",\"name\":\"BIOCABAZ - CABAZES BIOL\u00d3GICOS\",\"description\":\"O melhor que a terra d\u00e1 \u00e9 para si\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/biocabaz.pt\/web\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GALETES FINAS DE ARROZ INTEGRAL BIO LIMA","description":"GALETES FINAS DE ARROZ INTEGRAL BIO LIMA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.biocabaz.pt\/web\/en\/produto\/galetes-finas-de-arroz-integral-bio-lima\/","og_locale":"pt_PT","og_type":"article","og_title":"[:en]LIMA ORGANIC WHOLEGRAIN RICE CAKES[:pt]GALETES FINAS DE ARROZ INTEGRAL BIO LIMA[:] - BIOCABAZ - CABAZES BIOL\u00d3GICOS","og_description":"GALETES FINAS DE ARROZ INTEGRAL BIO LIMA","og_url":"https:\/\/biocabaz.pt\/web\/produto\/galetes-finas-de-arroz-integral-bio-lima\/","og_site_name":"BIOCABAZ - CABAZES BIOL\u00d3GICOS","article_modified_time":"2022-03-11T12:02:07+00:00","og_image":[{"width":512,"height":512,"url":"https:\/\/www.biocabaz.pt\/web\/wp-conteudos\/uploads\/2018\/10\/GALETES-FINAS-DE-ARROZ-INTEGRAL-BIO-LIMA.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.biocabaz.pt\/web\/en\/produto\/galetes-finas-de-arroz-integral-bio-lima\/","url":"https:\/\/www.biocabaz.pt\/web\/en\/produto\/galetes-finas-de-arroz-integral-bio-lima\/","name":"GALETES FINAS DE ARROZ INTEGRAL BIO LIMA","isPartOf":{"@id":"https:\/\/biocabaz.pt\/web\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.biocabaz.pt\/web\/en\/produto\/galetes-finas-de-arroz-integral-bio-lima\/#primaryimage"},"image":{"@id":"https:\/\/www.biocabaz.pt\/web\/en\/produto\/galetes-finas-de-arroz-integral-bio-lima\/#primaryimage"},"thumbnailUrl":"https:\/\/www.biocabaz.pt\/web\/wp-conteudos\/uploads\/2018\/10\/GALETES-FINAS-DE-ARROZ-INTEGRAL-BIO-LIMA.jpg","datePublished":"2018-10-23T15:45:28+00:00","dateModified":"2022-03-11T12:02:07+00:00","description":"GALETES FINAS DE ARROZ INTEGRAL BIO LIMA","breadcrumb":{"@id":"https:\/\/www.biocabaz.pt\/web\/en\/produto\/galetes-finas-de-arroz-integral-bio-lima\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.biocabaz.pt\/web\/en\/produto\/galetes-finas-de-arroz-integral-bio-lima\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.biocabaz.pt\/web\/en\/produto\/galetes-finas-de-arroz-integral-bio-lima\/#primaryimage","url":"https:\/\/www.biocabaz.pt\/web\/wp-conteudos\/uploads\/2018\/10\/GALETES-FINAS-DE-ARROZ-INTEGRAL-BIO-LIMA.jpg","contentUrl":"https:\/\/www.biocabaz.pt\/web\/wp-conteudos\/uploads\/2018\/10\/GALETES-FINAS-DE-ARROZ-INTEGRAL-BIO-LIMA.jpg","width":512,"height":512,"caption":"GALETES FINAS DE ARROZ INTEGRAL BIO LIMA"},{"@type":"BreadcrumbList","@id":"https:\/\/www.biocabaz.pt\/web\/en\/produto\/galetes-finas-de-arroz-integral-bio-lima\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/biocabaz.pt\/web\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/biocabaz.pt\/web\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"LIMA ORGANIC WHOLEGRAIN RICE CAKES"}]},{"@type":"WebSite","@id":"https:\/\/biocabaz.pt\/web\/en\/#website","url":"https:\/\/biocabaz.pt\/web\/en\/","name":"BIOCABAZ - CABAZES BIOL\u00d3GICOS","description":"O melhor que a terra d\u00e1 \u00e9 para si","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/biocabaz.pt\/web\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"}]}},"_links":{"self":[{"href":"https:\/\/biocabaz.pt\/web\/wp-json\/wp\/v2\/product\/9126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/biocabaz.pt\/web\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/biocabaz.pt\/web\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/biocabaz.pt\/web\/wp-json\/wp\/v2\/comments?post=9126"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/biocabaz.pt\/web\/wp-json\/wp\/v2\/media\/9127"}],"wp:attachment":[{"href":"https:\/\/biocabaz.pt\/web\/wp-json\/wp\/v2\/media?parent=9126"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/biocabaz.pt\/web\/wp-json\/wp\/v2\/product_cat?post=9126"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/biocabaz.pt\/web\/wp-json\/wp\/v2\/product_tag?post=9126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}