{"id":124216,"date":"2025-11-29T05:35:12","date_gmt":"2025-11-29T05:35:12","guid":{"rendered":"https:\/\/www.biocabaz.pt\/web\/?post_type=product&#038;p=124216"},"modified":"2025-11-29T05:36:21","modified_gmt":"2025-11-29T05:36:21","slug":"borrego-1-4-traseiro-bio-nacional-natal-peso-entre-2-a-3kg-encomendas-ate-dia-13-12","status":"publish","type":"product","link":"https:\/\/biocabaz.pt\/web\/produto\/borrego-1-4-traseiro-bio-nacional-natal-peso-entre-2-a-3kg-encomendas-ate-dia-13-12\/","title":{"rendered":"BORREGO 1\/4 TRASEIRO BIO NACIONAL NATAL ( PESO ENTRE 2 A 3KG) ENCOMENDAS ATE DIA 13\/12"},"content":{"rendered":"<p>Origem Portugal<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Origem Portugal<\/p>\n","protected":false},"featured_media":124218,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_cat":[14],"product_tag":[],"class_list":["post-124216","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-talho-biologico"],"bundle_layout":"","bundled_by":[],"bundled_items":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>BORREGO 1\/4 TRASEIRO BIO NACIONAL NATAL ( PESO ENTRE 2 A 3KG) ENCOMENDAS ATE DIA 13\/12<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.biocabaz.pt\/web\/en\/produto\/borrego-1-4-traseiro-bio-nacional-natal-peso-entre-2-a-3kg-encomendas-ate-dia-13-12\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:locale:alternate\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BORREGO 1\/4 TRASEIRO BIO NACIONAL NATAL ( PESO ENTRE 2 A 3KG) ENCOMENDAS ATE DIA 13\/12\" \/>\n<meta property=\"og:description\" content=\"Origem Portugal\" \/>\n<meta property=\"og:url\" content=\"https:\/\/biocabaz.pt\/web\/produto\/borrego-1-4-traseiro-bio-nacional-natal-peso-entre-2-a-3kg-encomendas-ate-dia-13-12\/\" \/>\n<meta property=\"og:site_name\" content=\"BIOCABAZ - CABAZES BIOL\u00d3GICOS\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-29T05:36:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.biocabaz.pt\/web\/wp-conteudos\/uploads\/2025\/11\/borrego-dianteiro-bio-nacional.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.biocabaz.pt\/web\/en\/produto\/borrego-1-4-traseiro-bio-nacional-natal-peso-entre-2-a-3kg-encomendas-ate-dia-13-12\/\",\"url\":\"https:\/\/www.biocabaz.pt\/web\/en\/produto\/borrego-1-4-traseiro-bio-nacional-natal-peso-entre-2-a-3kg-encomendas-ate-dia-13-12\/\",\"name\":\"BORREGO 1\/4 TRASEIRO BIO NACIONAL NATAL ( PESO ENTRE 2 A 3KG) ENCOMENDAS ATE DIA 13\/12\",\"isPartOf\":{\"@id\":\"https:\/\/biocabaz.pt\/web\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.biocabaz.pt\/web\/en\/produto\/borrego-1-4-traseiro-bio-nacional-natal-peso-entre-2-a-3kg-encomendas-ate-dia-13-12\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.biocabaz.pt\/web\/en\/produto\/borrego-1-4-traseiro-bio-nacional-natal-peso-entre-2-a-3kg-encomendas-ate-dia-13-12\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.biocabaz.pt\/web\/wp-conteudos\/uploads\/2025\/11\/borrego-dianteiro-bio-nacional.png\",\"datePublished\":\"2025-11-29T05:35:12+00:00\",\"dateModified\":\"2025-11-29T05:36:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.biocabaz.pt\/web\/en\/produto\/borrego-1-4-traseiro-bio-nacional-natal-peso-entre-2-a-3kg-encomendas-ate-dia-13-12\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.biocabaz.pt\/web\/en\/produto\/borrego-1-4-traseiro-bio-nacional-natal-peso-entre-2-a-3kg-encomendas-ate-dia-13-12\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/www.biocabaz.pt\/web\/en\/produto\/borrego-1-4-traseiro-bio-nacional-natal-peso-entre-2-a-3kg-encomendas-ate-dia-13-12\/#primaryimage\",\"url\":\"https:\/\/www.biocabaz.pt\/web\/wp-conteudos\/uploads\/2025\/11\/borrego-dianteiro-bio-nacional.png\",\"contentUrl\":\"https:\/\/www.biocabaz.pt\/web\/wp-conteudos\/uploads\/2025\/11\/borrego-dianteiro-bio-nacional.png\",\"width\":800,\"height\":600,\"caption\":\"borrego-traseiro-bio-nacional\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.biocabaz.pt\/web\/en\/produto\/borrego-1-4-traseiro-bio-nacional-natal-peso-entre-2-a-3kg-encomendas-ate-dia-13-12\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/biocabaz.pt\/web\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/biocabaz.pt\/web\/en\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"BORREGO 1\/4 TRASEIRO BIO NACIONAL NATAL ( PESO ENTRE 2 A 3KG) ENCOMENDAS ATE DIA 13\/12\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/biocabaz.pt\/web\/en\/#website\",\"url\":\"https:\/\/biocabaz.pt\/web\/en\/\",\"name\":\"BIOCABAZ - CABAZES BIOL\u00d3GICOS\",\"description\":\"O melhor que a terra d\u00e1 \u00e9 para si\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/biocabaz.pt\/web\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BORREGO 1\/4 TRASEIRO BIO NACIONAL NATAL ( PESO ENTRE 2 A 3KG) ENCOMENDAS ATE DIA 13\/12","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.biocabaz.pt\/web\/en\/produto\/borrego-1-4-traseiro-bio-nacional-natal-peso-entre-2-a-3kg-encomendas-ate-dia-13-12\/","og_locale":"pt_PT","og_type":"article","og_title":"[:pt]BORREGO 1\/4 TRASEIRO BIO NACIONAL NATAL ( PESO ENTRE 2 A 3KG) ENCOMENDAS ATE DIA 13\/12[:] - BIOCABAZ - CABAZES BIOL\u00d3GICOS","og_description":"Origem Portugal","og_url":"https:\/\/biocabaz.pt\/web\/produto\/borrego-1-4-traseiro-bio-nacional-natal-peso-entre-2-a-3kg-encomendas-ate-dia-13-12\/","og_site_name":"BIOCABAZ - CABAZES BIOL\u00d3GICOS","article_modified_time":"2025-11-29T05:36:21+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/www.biocabaz.pt\/web\/wp-conteudos\/uploads\/2025\/11\/borrego-dianteiro-bio-nacional.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.biocabaz.pt\/web\/en\/produto\/borrego-1-4-traseiro-bio-nacional-natal-peso-entre-2-a-3kg-encomendas-ate-dia-13-12\/","url":"https:\/\/www.biocabaz.pt\/web\/en\/produto\/borrego-1-4-traseiro-bio-nacional-natal-peso-entre-2-a-3kg-encomendas-ate-dia-13-12\/","name":"BORREGO 1\/4 TRASEIRO BIO NACIONAL NATAL ( PESO ENTRE 2 A 3KG) ENCOMENDAS ATE DIA 13\/12","isPartOf":{"@id":"https:\/\/biocabaz.pt\/web\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.biocabaz.pt\/web\/en\/produto\/borrego-1-4-traseiro-bio-nacional-natal-peso-entre-2-a-3kg-encomendas-ate-dia-13-12\/#primaryimage"},"image":{"@id":"https:\/\/www.biocabaz.pt\/web\/en\/produto\/borrego-1-4-traseiro-bio-nacional-natal-peso-entre-2-a-3kg-encomendas-ate-dia-13-12\/#primaryimage"},"thumbnailUrl":"https:\/\/www.biocabaz.pt\/web\/wp-conteudos\/uploads\/2025\/11\/borrego-dianteiro-bio-nacional.png","datePublished":"2025-11-29T05:35:12+00:00","dateModified":"2025-11-29T05:36:21+00:00","breadcrumb":{"@id":"https:\/\/www.biocabaz.pt\/web\/en\/produto\/borrego-1-4-traseiro-bio-nacional-natal-peso-entre-2-a-3kg-encomendas-ate-dia-13-12\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.biocabaz.pt\/web\/en\/produto\/borrego-1-4-traseiro-bio-nacional-natal-peso-entre-2-a-3kg-encomendas-ate-dia-13-12\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.biocabaz.pt\/web\/en\/produto\/borrego-1-4-traseiro-bio-nacional-natal-peso-entre-2-a-3kg-encomendas-ate-dia-13-12\/#primaryimage","url":"https:\/\/www.biocabaz.pt\/web\/wp-conteudos\/uploads\/2025\/11\/borrego-dianteiro-bio-nacional.png","contentUrl":"https:\/\/www.biocabaz.pt\/web\/wp-conteudos\/uploads\/2025\/11\/borrego-dianteiro-bio-nacional.png","width":800,"height":600,"caption":"borrego-traseiro-bio-nacional"},{"@type":"BreadcrumbList","@id":"https:\/\/www.biocabaz.pt\/web\/en\/produto\/borrego-1-4-traseiro-bio-nacional-natal-peso-entre-2-a-3kg-encomendas-ate-dia-13-12\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/biocabaz.pt\/web\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/biocabaz.pt\/web\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"BORREGO 1\/4 TRASEIRO BIO NACIONAL NATAL ( PESO ENTRE 2 A 3KG) ENCOMENDAS ATE DIA 13\/12"}]},{"@type":"WebSite","@id":"https:\/\/biocabaz.pt\/web\/en\/#website","url":"https:\/\/biocabaz.pt\/web\/en\/","name":"BIOCABAZ - CABAZES BIOL\u00d3GICOS","description":"O melhor que a terra d\u00e1 \u00e9 para si","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/biocabaz.pt\/web\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"}]}},"_links":{"self":[{"href":"https:\/\/biocabaz.pt\/web\/wp-json\/wp\/v2\/product\/124216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/biocabaz.pt\/web\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/biocabaz.pt\/web\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/biocabaz.pt\/web\/wp-json\/wp\/v2\/comments?post=124216"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/biocabaz.pt\/web\/wp-json\/wp\/v2\/media\/124218"}],"wp:attachment":[{"href":"https:\/\/biocabaz.pt\/web\/wp-json\/wp\/v2\/media?parent=124216"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/biocabaz.pt\/web\/wp-json\/wp\/v2\/product_cat?post=124216"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/biocabaz.pt\/web\/wp-json\/wp\/v2\/product_tag?post=124216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}